{"id":59176,"date":"2026-05-12T19:30:40","date_gmt":"2026-05-12T19:30:40","guid":{"rendered":"https:\/\/defrentealaverdad.com\/?p=59176"},"modified":"2026-05-12T23:31:50","modified_gmt":"2026-05-12T23:31:50","slug":"editora-poetas-de-la-era-presenta-doble-jornada-cultural-en-casa-libros-rd","status":"publish","type":"post","link":"https:\/\/defrentealaverdad.com\/index.php\/2026\/05\/12\/editora-poetas-de-la-era-presenta-doble-jornada-cultural-en-casa-libros-rd\/","title":{"rendered":"Editora Poetas de la Era presenta doble jornada cultural en Casa Libros RD"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Santo Domingo.\u2013<\/strong> La Editora Poetas de la Era celebrar\u00e1 este s\u00e1bado 16 de mayo una doble jornada cultural en el Centro Cultural Casa Libros RD, en Gazcue, con actividades enfocadas en la literatura, la maternidad y el proceso creativo en las artes esc\u00e9nicas.<\/p>\n<p style=\"text-align: justify;\">La programaci\u00f3n iniciar\u00e1 a las 3:00 de la tarde con el conversatorio-recital \u201cEl proceso del actor: explorando el proceso de la gu\u00eda desde el actor hacia el personaje\u201d, a cargo de la actriz y autora Pachy M\u00e9ndez, quien abordar\u00e1 su experiencia en la construcci\u00f3n de personajes y la conexi\u00f3n entre el texto y la interpretaci\u00f3n emocional.<\/p>\n<p style=\"text-align: justify;\">Posteriormente, a las 4:00 de la tarde, se desarrollar\u00e1 el panel \u201cLiteratura y maternidad: pujar textos desde las entra\u00f1as\u201d, espacio que reunir\u00e1 a las escritoras M\u00e1xima Hern\u00e1ndez, Patricia Minalla, Mar\u00eda del Carmen Villafa\u00f1a y Leibi NG, bajo la moderaci\u00f3n de Johanna Ramos.<\/p>\n<p style=\"text-align: justify;\">Durante el encuentro se analizar\u00e1n los desaf\u00edos que enfrentan las mujeres escritoras al combinar la creaci\u00f3n literaria con las responsabilidades familiares y sociales, as\u00ed como la manera en que la maternidad transforma la voz narrativa y los procesos de escritura.<\/p>\n<p style=\"text-align: justify;\">La jornada concluir\u00e1 con un micr\u00f3fono abierto, donde los asistentes podr\u00e1n compartir poemas, textos y escritos originales en intervenciones de hasta dos minutos.<\/p>\n<p style=\"text-align: justify;\">La actividad forma parte de las iniciativas impulsadas por la Editora Poetas de la Era para promover espacios de reflexi\u00f3n, intercambio cultural y difusi\u00f3n de las artes literarias y esc\u00e9nicas en Rep\u00fablica Dominicana.<\/p>\n<p>Fuente: Prensa Poetas de la Era<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.\u2013 La Editora Poetas de la Era celebrar\u00e1 este s\u00e1bado 16 de mayo una<\/p>\n","protected":false},"author":4,"featured_media":59177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[245],"tags":[],"class_list":["post-59176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/defrentealaverdad.com\/index.php\/wp-json\/wp\/v2\/posts\/59176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/defrentealaverdad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/defrentealaverdad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/defrentealaverdad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/defrentealaverdad.com\/index.php\/wp-json\/wp\/v2\/comments?post=59176"}],"version-history":[{"count":1,"href":"https:\/\/defrentealaverdad.com\/index.php\/wp-json\/wp\/v2\/posts\/59176\/revisions"}],"predecessor-version":[{"id":59178,"href":"https:\/\/defrentealaverdad.com\/index.php\/wp-json\/wp\/v2\/posts\/59176\/revisions\/59178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/defrentealaverdad.com\/index.php\/wp-json\/wp\/v2\/media\/59177"}],"wp:attachment":[{"href":"https:\/\/defrentealaverdad.com\/index.php\/wp-json\/wp\/v2\/media?parent=59176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/defrentealaverdad.com\/index.php\/wp-json\/wp\/v2\/categories?post=59176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/defrentealaverdad.com\/index.php\/wp-json\/wp\/v2\/tags?post=59176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}